{"id":9289,"date":"2021-04-30T11:42:08","date_gmt":"2021-04-30T11:42:08","guid":{"rendered":"https:\/\/www.solidaridadobrera.org\/confederal\/?p=9289"},"modified":"2021-04-30T11:42:09","modified_gmt":"2021-04-30T11:42:09","slug":"tablas-salariales-mensualizadas-l-p-v-2021-madrid","status":"publish","type":"post","link":"https:\/\/www.solidaridadobrera.org\/confederal\/2021\/04\/30\/tablas-salariales-mensualizadas-l-p-v-2021-madrid\/","title":{"rendered":"Tablas salariales mensualizadas l.p.v. 2021 Madrid"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"9289\" class=\"elementor elementor-9289\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-d3c9744 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"d3c9744\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-129d0da\" data-id=\"129d0da\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-13fc1cf elementor-arrows-position-inside elementor-pagination-position-outside elementor-widget elementor-widget-image-carousel\" data-id=\"13fc1cf\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;slides_to_show&quot;:&quot;1&quot;,&quot;navigation&quot;:&quot;both&quot;,&quot;autoplay&quot;:&quot;yes&quot;,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;autoplay_speed&quot;:5000,&quot;infinite&quot;:&quot;yes&quot;,&quot;effect&quot;:&quot;slide&quot;,&quot;speed&quot;:500}\" data-widget_type=\"image-carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-image-carousel-wrapper swiper\" role=\"region\" aria-roledescription=\"carousel\" aria-label=\"Carrusel de im\u00e1genes\" dir=\"ltr\">\n\t\t\t<div class=\"elementor-image-carousel swiper-wrapper\" aria-live=\"off\">\n\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"1 de 10\"><a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"13fc1cf\" data-elementor-lightbox-title=\"tablasMensualizadas\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6OTI5NywidXJsIjoiaHR0cHM6XC9cL3d3dy5zb2xpZGFyaWRhZG9icmVyYS5vcmdcL2NvbmZlZGVyYWxcL3dwLWNvbnRlbnRcL3VwbG9hZHNcLzIwMjFcLzA0XC90YWJsYXNNZW5zdWFsaXphZGFzLnBuZyIsInNsaWRlc2hvdyI6IjEzZmMxY2YifQ%3D%3D\" href=\"https:\/\/www.solidaridadobrera.org\/confederal\/wp-content\/uploads\/2021\/04\/tablasMensualizadas.png\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.solidaridadobrera.org\/confederal\/wp-content\/uploads\/2021\/04\/tablasMensualizadas-1024x723.png\" alt=\"tabla mensualizada tiempo total\" \/><\/figure><\/a><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"2 de 10\"><a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"13fc1cf\" data-elementor-lightbox-title=\"tablasPeonDia\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6OTI5OCwidXJsIjoiaHR0cHM6XC9cL3d3dy5zb2xpZGFyaWRhZG9icmVyYS5vcmdcL2NvbmZlZGVyYWxcL3dwLWNvbnRlbnRcL3VwbG9hZHNcLzIwMjFcLzA0XC90YWJsYXNQZW9uRGlhLnBuZyIsInNsaWRlc2hvdyI6IjEzZmMxY2YifQ%3D%3D\" href=\"https:\/\/www.solidaridadobrera.org\/confederal\/wp-content\/uploads\/2021\/04\/tablasPeonDia.png\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.solidaridadobrera.org\/confederal\/wp-content\/uploads\/2021\/04\/tablasPeonDia-1024x728.png\" alt=\"tabla mensualizada pe\u00f3n dia tiempo parcial\" \/><\/figure><\/a><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"3 de 10\"><a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"13fc1cf\" data-elementor-lightbox-title=\"peonNocheParcial\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6OTI5NiwidXJsIjoiaHR0cHM6XC9cL3d3dy5zb2xpZGFyaWRhZG9icmVyYS5vcmdcL2NvbmZlZGVyYWxcL3dwLWNvbnRlbnRcL3VwbG9hZHNcLzIwMjFcLzA0XC9wZW9uTm9jaGVQYXJjaWFsLnBuZyIsInNsaWRlc2hvdyI6IjEzZmMxY2YifQ%3D%3D\" href=\"https:\/\/www.solidaridadobrera.org\/confederal\/wp-content\/uploads\/2021\/04\/peonNocheParcial.png\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.solidaridadobrera.org\/confederal\/wp-content\/uploads\/2021\/04\/peonNocheParcial-1024x728.png\" alt=\"tabla mensualizada pe\u00f3n noche tiempo parcial\" \/><\/figure><\/a><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"4 de 10\"><a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"13fc1cf\" data-elementor-lightbox-title=\"conductorDiaParcial\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6OTI5MywidXJsIjoiaHR0cHM6XC9cL3d3dy5zb2xpZGFyaWRhZG9icmVyYS5vcmdcL2NvbmZlZGVyYWxcL3dwLWNvbnRlbnRcL3VwbG9hZHNcLzIwMjFcLzA0XC9jb25kdWN0b3JEaWFQYXJjaWFsLnBuZyIsInNsaWRlc2hvdyI6IjEzZmMxY2YifQ%3D%3D\" href=\"https:\/\/www.solidaridadobrera.org\/confederal\/wp-content\/uploads\/2021\/04\/conductorDiaParcial.png\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.solidaridadobrera.org\/confederal\/wp-content\/uploads\/2021\/04\/conductorDiaParcial-1024x728.png\" alt=\"tabla mensualizada conductor dia tiempo parcial\" \/><\/figure><\/a><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"5 de 10\"><a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"13fc1cf\" data-elementor-lightbox-title=\"conductorNocheParcial\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6OTMxMSwidXJsIjoiaHR0cHM6XC9cL3d3dy5zb2xpZGFyaWRhZG9icmVyYS5vcmdcL2NvbmZlZGVyYWxcL3dwLWNvbnRlbnRcL3VwbG9hZHNcLzIwMjFcLzA0XC9jb25kdWN0b3JOb2NoZVBhcmNpYWwucG5nIiwic2xpZGVzaG93IjoiMTNmYzFjZiJ9\" href=\"https:\/\/www.solidaridadobrera.org\/confederal\/wp-content\/uploads\/2021\/04\/conductorNocheParcial.png\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.solidaridadobrera.org\/confederal\/wp-content\/uploads\/2021\/04\/conductorNocheParcial-1024x728.png\" alt=\"tabla mensualizada conductor noche tiempo parcial\" \/><\/figure><\/a><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"6 de 10\"><a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"13fc1cf\" data-elementor-lightbox-title=\"capatazDiaParcial\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6OTI5MiwidXJsIjoiaHR0cHM6XC9cL3d3dy5zb2xpZGFyaWRhZG9icmVyYS5vcmdcL2NvbmZlZGVyYWxcL3dwLWNvbnRlbnRcL3VwbG9hZHNcLzIwMjFcLzA0XC9jYXBhdGF6RGlhUGFyY2lhbC5wbmciLCJzbGlkZXNob3ciOiIxM2ZjMWNmIn0%3D\" href=\"https:\/\/www.solidaridadobrera.org\/confederal\/wp-content\/uploads\/2021\/04\/capatazDiaParcial.png\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.solidaridadobrera.org\/confederal\/wp-content\/uploads\/2021\/04\/capatazDiaParcial-1024x728.png\" alt=\"tabla mensualizada capataz dia tiempo parcial\" \/><\/figure><\/a><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"7 de 10\"><a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"13fc1cf\" data-elementor-lightbox-title=\"capatazNocheParcial\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6OTMwMiwidXJsIjoiaHR0cHM6XC9cL3d3dy5zb2xpZGFyaWRhZG9icmVyYS5vcmdcL2NvbmZlZGVyYWxcL3dwLWNvbnRlbnRcL3VwbG9hZHNcLzIwMjFcLzA0XC9jYXBhdGF6Tm9jaGVQYXJjaWFsLnBuZyIsInNsaWRlc2hvdyI6IjEzZmMxY2YifQ%3D%3D\" href=\"https:\/\/www.solidaridadobrera.org\/confederal\/wp-content\/uploads\/2021\/04\/capatazNocheParcial.png\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.solidaridadobrera.org\/confederal\/wp-content\/uploads\/2021\/04\/capatazNocheParcial-1024x728.png\" alt=\"tabla mensualizada capataz noche tiempo parcial\" \/><\/figure><\/a><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"8 de 10\"><a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"13fc1cf\" data-elementor-lightbox-title=\"taller3parcial\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6OTMwMSwidXJsIjoiaHR0cHM6XC9cL3d3dy5zb2xpZGFyaWRhZG9icmVyYS5vcmdcL2NvbmZlZGVyYWxcL3dwLWNvbnRlbnRcL3VwbG9hZHNcLzIwMjFcLzA0XC90YWxsZXIzcGFyY2lhbC5wbmciLCJzbGlkZXNob3ciOiIxM2ZjMWNmIn0%3D\" href=\"https:\/\/www.solidaridadobrera.org\/confederal\/wp-content\/uploads\/2021\/04\/taller3parcial.png\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.solidaridadobrera.org\/confederal\/wp-content\/uploads\/2021\/04\/taller3parcial-1024x728.png\" alt=\"tabla mensualizada 3\u00aa taller tiempo parcial\" \/><\/figure><\/a><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"9 de 10\"><a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"13fc1cf\" data-elementor-lightbox-title=\"taller2Parcial\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6OTMwMCwidXJsIjoiaHR0cHM6XC9cL3d3dy5zb2xpZGFyaWRhZG9icmVyYS5vcmdcL2NvbmZlZGVyYWxcL3dwLWNvbnRlbnRcL3VwbG9hZHNcLzIwMjFcLzA0XC90YWxsZXIyUGFyY2lhbC5wbmciLCJzbGlkZXNob3ciOiIxM2ZjMWNmIn0%3D\" href=\"https:\/\/www.solidaridadobrera.org\/confederal\/wp-content\/uploads\/2021\/04\/taller2Parcial.png\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.solidaridadobrera.org\/confederal\/wp-content\/uploads\/2021\/04\/taller2Parcial-1024x728.png\" alt=\"tabla mensualizada 2\u00aa taller tiempo parcial\" \/><\/figure><\/a><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"10 de 10\"><a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"13fc1cf\" data-elementor-lightbox-title=\"taller1Parcial\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6OTI5OSwidXJsIjoiaHR0cHM6XC9cL3d3dy5zb2xpZGFyaWRhZG9icmVyYS5vcmdcL2NvbmZlZGVyYWxcL3dwLWNvbnRlbnRcL3VwbG9hZHNcLzIwMjFcLzA0XC90YWxsZXIxUGFyY2lhbC5wbmciLCJzbGlkZXNob3ciOiIxM2ZjMWNmIn0%3D\" href=\"https:\/\/www.solidaridadobrera.org\/confederal\/wp-content\/uploads\/2021\/04\/taller1Parcial.png\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.solidaridadobrera.org\/confederal\/wp-content\/uploads\/2021\/04\/taller1Parcial-1024x728.png\" alt=\"tabla mensualizada 1\u00aa taller tiempo parcial\" \/><\/figure><\/a><\/div>\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-prev\" role=\"button\" tabindex=\"0\">\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-left\"><\/i>\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-next\" role=\"button\" tabindex=\"0\">\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-right\"><\/i>\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"swiper-pagination\"><\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Anterior Siguiente<\/p>\n","protected":false},"author":10,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"postBodyCss":"","postBodyMargin":[],"postBodyPadding":[],"postBodyBackground":{"backgroundType":"classic","gradient":""},"ngg_post_thumbnail":0,"footnotes":""},"categories":[204,129],"tags":[678],"class_list":["post-9289","post","type-post","status-publish","format-standard","hentry","category-limpieza-viaria-madrid","category-table-anuncios-limpieza-table-anuncios-limpieza","tag-tablas-mensualizadas-lpv"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Tablas salariales mensualizadas l.p.v. 2021 Madrid - CONFEDERACI\u00d3N SOLIDARIDAD OBRERA<\/title>\n<meta name=\"description\" content=\"Pod\u00e9is consultar las tablas salariales mensualizadas para el colectivo de limpieza p\u00fablica viaria de Madrid capital.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.solidaridadobrera.org\/confederal\/2021\/04\/30\/tablas-salariales-mensualizadas-l-p-v-2021-madrid\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Tablas salariales mensualizadas l.p.v. 2021 Madrid - CONFEDERACI\u00d3N SOLIDARIDAD OBRERA\" \/>\n<meta property=\"og:description\" content=\"Pod\u00e9is consultar las tablas salariales mensualizadas para el colectivo de limpieza p\u00fablica viaria de Madrid capital.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.solidaridadobrera.org\/confederal\/2021\/04\/30\/tablas-salariales-mensualizadas-l-p-v-2021-madrid\/\" \/>\n<meta property=\"og:site_name\" content=\"CONFEDERACI\u00d3N SOLIDARIDAD OBRERA\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/es-es.facebook.com\/Soliobrera\" \/>\n<meta property=\"article:published_time\" content=\"2021-04-30T11:42:08+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-04-30T11:42:09+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.solidaridadobrera.org\/confederal\/wp-content\/uploads\/2021\/04\/tablasMensualizadas-1024x723.png\" \/>\n<meta name=\"author\" content=\"Kin_\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Kin_\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.solidaridadobrera.org\\\/confederal\\\/2021\\\/04\\\/30\\\/tablas-salariales-mensualizadas-l-p-v-2021-madrid\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.solidaridadobrera.org\\\/confederal\\\/2021\\\/04\\\/30\\\/tablas-salariales-mensualizadas-l-p-v-2021-madrid\\\/\"},\"author\":{\"name\":\"Kin_\",\"@id\":\"https:\\\/\\\/www.solidaridadobrera.org\\\/confederal\\\/#\\\/schema\\\/person\\\/a9893999c35a05e0d32b4cf519d3cc62\"},\"headline\":\"Tablas salariales mensualizadas l.p.v. 2021 Madrid\",\"datePublished\":\"2021-04-30T11:42:08+00:00\",\"dateModified\":\"2021-04-30T11:42:09+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.solidaridadobrera.org\\\/confederal\\\/2021\\\/04\\\/30\\\/tablas-salariales-mensualizadas-l-p-v-2021-madrid\\\/\"},\"wordCount\":9,\"commentCount\":2,\"publisher\":{\"@id\":\"https:\\\/\\\/www.solidaridadobrera.org\\\/confederal\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.solidaridadobrera.org\\\/confederal\\\/2021\\\/04\\\/30\\\/tablas-salariales-mensualizadas-l-p-v-2021-madrid\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.solidaridadobrera.org\\\/confederal\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/tablasMensualizadas-1024x723.png\",\"keywords\":[\"tablas mensualizadas LPV\"],\"articleSection\":[\"Limpieza Viaria Madrid\",\"Tabl\u00f3n de Anuncios Limpieza\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.solidaridadobrera.org\\\/confederal\\\/2021\\\/04\\\/30\\\/tablas-salariales-mensualizadas-l-p-v-2021-madrid\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.solidaridadobrera.org\\\/confederal\\\/2021\\\/04\\\/30\\\/tablas-salariales-mensualizadas-l-p-v-2021-madrid\\\/\",\"url\":\"https:\\\/\\\/www.solidaridadobrera.org\\\/confederal\\\/2021\\\/04\\\/30\\\/tablas-salariales-mensualizadas-l-p-v-2021-madrid\\\/\",\"name\":\"Tablas salariales mensualizadas l.p.v. 2021 Madrid - CONFEDERACI\u00d3N SOLIDARIDAD OBRERA\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.solidaridadobrera.org\\\/confederal\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.solidaridadobrera.org\\\/confederal\\\/2021\\\/04\\\/30\\\/tablas-salariales-mensualizadas-l-p-v-2021-madrid\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.solidaridadobrera.org\\\/confederal\\\/2021\\\/04\\\/30\\\/tablas-salariales-mensualizadas-l-p-v-2021-madrid\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.solidaridadobrera.org\\\/confederal\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/tablasMensualizadas-1024x723.png\",\"datePublished\":\"2021-04-30T11:42:08+00:00\",\"dateModified\":\"2021-04-30T11:42:09+00:00\",\"description\":\"Pod\u00e9is consultar las tablas salariales mensualizadas para el colectivo de limpieza p\u00fablica viaria de Madrid capital.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.solidaridadobrera.org\\\/confederal\\\/2021\\\/04\\\/30\\\/tablas-salariales-mensualizadas-l-p-v-2021-madrid\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.solidaridadobrera.org\\\/confederal\\\/2021\\\/04\\\/30\\\/tablas-salariales-mensualizadas-l-p-v-2021-madrid\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.solidaridadobrera.org\\\/confederal\\\/2021\\\/04\\\/30\\\/tablas-salariales-mensualizadas-l-p-v-2021-madrid\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.solidaridadobrera.org\\\/confederal\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/tablasMensualizadas.png\",\"contentUrl\":\"https:\\\/\\\/www.solidaridadobrera.org\\\/confederal\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/tablasMensualizadas.png\",\"width\":1600,\"height\":1130,\"caption\":\"tabla mensualizada tiempo total\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.solidaridadobrera.org\\\/confederal\\\/2021\\\/04\\\/30\\\/tablas-salariales-mensualizadas-l-p-v-2021-madrid\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.solidaridadobrera.org\\\/confederal\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Tablas salariales mensualizadas l.p.v. 2021 Madrid\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.solidaridadobrera.org\\\/confederal\\\/#website\",\"url\":\"https:\\\/\\\/www.solidaridadobrera.org\\\/confederal\\\/\",\"name\":\"SOLIDARIDAD OBRERA\",\"description\":\"Confederaci\u00f3n Anarcosindicalista. La lucha es el \u00fanico camino.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.solidaridadobrera.org\\\/confederal\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.solidaridadobrera.org\\\/confederal\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.solidaridadobrera.org\\\/confederal\\\/#organization\",\"name\":\"SUT Solidaridad Obrera\",\"url\":\"https:\\\/\\\/www.solidaridadobrera.org\\\/confederal\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.solidaridadobrera.org\\\/confederal\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.solidaridadobrera.org\\\/confederal\\\/wp-content\\\/uploads\\\/2021\\\/07\\\/logo_soli_web.png\",\"contentUrl\":\"https:\\\/\\\/www.solidaridadobrera.org\\\/confederal\\\/wp-content\\\/uploads\\\/2021\\\/07\\\/logo_soli_web.png\",\"width\":1181,\"height\":1181,\"caption\":\"SUT Solidaridad Obrera\"},\"image\":{\"@id\":\"https:\\\/\\\/www.solidaridadobrera.org\\\/confederal\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/es-es.facebook.com\\\/Soliobrera\",\"https:\\\/\\\/www.instagram.com\\\/soliobrera\\\/\",\"https:\\\/\\\/web.telegram.org\\\/a\\\/#-1001124968543\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.solidaridadobrera.org\\\/confederal\\\/#\\\/schema\\\/person\\\/a9893999c35a05e0d32b4cf519d3cc62\",\"name\":\"Kin_\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f0b2c9f275a8e8670cca4a5dad715bd7d47843fb27cd0a30aea4b99dc03a2b8f?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f0b2c9f275a8e8670cca4a5dad715bd7d47843fb27cd0a30aea4b99dc03a2b8f?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f0b2c9f275a8e8670cca4a5dad715bd7d47843fb27cd0a30aea4b99dc03a2b8f?s=96&d=mm&r=g\",\"caption\":\"Kin_\"},\"url\":\"https:\\\/\\\/www.solidaridadobrera.org\\\/confederal\\\/author\\\/joaquin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Tablas salariales mensualizadas l.p.v. 2021 Madrid - CONFEDERACI\u00d3N SOLIDARIDAD OBRERA","description":"Pod\u00e9is consultar las tablas salariales mensualizadas para el colectivo de limpieza p\u00fablica viaria de Madrid capital.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.solidaridadobrera.org\/confederal\/2021\/04\/30\/tablas-salariales-mensualizadas-l-p-v-2021-madrid\/","og_locale":"es_ES","og_type":"article","og_title":"Tablas salariales mensualizadas l.p.v. 2021 Madrid - CONFEDERACI\u00d3N SOLIDARIDAD OBRERA","og_description":"Pod\u00e9is consultar las tablas salariales mensualizadas para el colectivo de limpieza p\u00fablica viaria de Madrid capital.","og_url":"https:\/\/www.solidaridadobrera.org\/confederal\/2021\/04\/30\/tablas-salariales-mensualizadas-l-p-v-2021-madrid\/","og_site_name":"CONFEDERACI\u00d3N SOLIDARIDAD OBRERA","article_publisher":"https:\/\/es-es.facebook.com\/Soliobrera","article_published_time":"2021-04-30T11:42:08+00:00","article_modified_time":"2021-04-30T11:42:09+00:00","og_image":[{"url":"https:\/\/www.solidaridadobrera.org\/confederal\/wp-content\/uploads\/2021\/04\/tablasMensualizadas-1024x723.png","type":"","width":"","height":""}],"author":"Kin_","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Kin_","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.solidaridadobrera.org\/confederal\/2021\/04\/30\/tablas-salariales-mensualizadas-l-p-v-2021-madrid\/#article","isPartOf":{"@id":"https:\/\/www.solidaridadobrera.org\/confederal\/2021\/04\/30\/tablas-salariales-mensualizadas-l-p-v-2021-madrid\/"},"author":{"name":"Kin_","@id":"https:\/\/www.solidaridadobrera.org\/confederal\/#\/schema\/person\/a9893999c35a05e0d32b4cf519d3cc62"},"headline":"Tablas salariales mensualizadas l.p.v. 2021 Madrid","datePublished":"2021-04-30T11:42:08+00:00","dateModified":"2021-04-30T11:42:09+00:00","mainEntityOfPage":{"@id":"https:\/\/www.solidaridadobrera.org\/confederal\/2021\/04\/30\/tablas-salariales-mensualizadas-l-p-v-2021-madrid\/"},"wordCount":9,"commentCount":2,"publisher":{"@id":"https:\/\/www.solidaridadobrera.org\/confederal\/#organization"},"image":{"@id":"https:\/\/www.solidaridadobrera.org\/confederal\/2021\/04\/30\/tablas-salariales-mensualizadas-l-p-v-2021-madrid\/#primaryimage"},"thumbnailUrl":"https:\/\/www.solidaridadobrera.org\/confederal\/wp-content\/uploads\/2021\/04\/tablasMensualizadas-1024x723.png","keywords":["tablas mensualizadas LPV"],"articleSection":["Limpieza Viaria Madrid","Tabl\u00f3n de Anuncios Limpieza"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.solidaridadobrera.org\/confederal\/2021\/04\/30\/tablas-salariales-mensualizadas-l-p-v-2021-madrid\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.solidaridadobrera.org\/confederal\/2021\/04\/30\/tablas-salariales-mensualizadas-l-p-v-2021-madrid\/","url":"https:\/\/www.solidaridadobrera.org\/confederal\/2021\/04\/30\/tablas-salariales-mensualizadas-l-p-v-2021-madrid\/","name":"Tablas salariales mensualizadas l.p.v. 2021 Madrid - CONFEDERACI\u00d3N SOLIDARIDAD OBRERA","isPartOf":{"@id":"https:\/\/www.solidaridadobrera.org\/confederal\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.solidaridadobrera.org\/confederal\/2021\/04\/30\/tablas-salariales-mensualizadas-l-p-v-2021-madrid\/#primaryimage"},"image":{"@id":"https:\/\/www.solidaridadobrera.org\/confederal\/2021\/04\/30\/tablas-salariales-mensualizadas-l-p-v-2021-madrid\/#primaryimage"},"thumbnailUrl":"https:\/\/www.solidaridadobrera.org\/confederal\/wp-content\/uploads\/2021\/04\/tablasMensualizadas-1024x723.png","datePublished":"2021-04-30T11:42:08+00:00","dateModified":"2021-04-30T11:42:09+00:00","description":"Pod\u00e9is consultar las tablas salariales mensualizadas para el colectivo de limpieza p\u00fablica viaria de Madrid capital.","breadcrumb":{"@id":"https:\/\/www.solidaridadobrera.org\/confederal\/2021\/04\/30\/tablas-salariales-mensualizadas-l-p-v-2021-madrid\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.solidaridadobrera.org\/confederal\/2021\/04\/30\/tablas-salariales-mensualizadas-l-p-v-2021-madrid\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.solidaridadobrera.org\/confederal\/2021\/04\/30\/tablas-salariales-mensualizadas-l-p-v-2021-madrid\/#primaryimage","url":"https:\/\/www.solidaridadobrera.org\/confederal\/wp-content\/uploads\/2021\/04\/tablasMensualizadas.png","contentUrl":"https:\/\/www.solidaridadobrera.org\/confederal\/wp-content\/uploads\/2021\/04\/tablasMensualizadas.png","width":1600,"height":1130,"caption":"tabla mensualizada tiempo total"},{"@type":"BreadcrumbList","@id":"https:\/\/www.solidaridadobrera.org\/confederal\/2021\/04\/30\/tablas-salariales-mensualizadas-l-p-v-2021-madrid\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.solidaridadobrera.org\/confederal\/"},{"@type":"ListItem","position":2,"name":"Tablas salariales mensualizadas l.p.v. 2021 Madrid"}]},{"@type":"WebSite","@id":"https:\/\/www.solidaridadobrera.org\/confederal\/#website","url":"https:\/\/www.solidaridadobrera.org\/confederal\/","name":"SOLIDARIDAD OBRERA","description":"Confederaci\u00f3n Anarcosindicalista. La lucha es el \u00fanico camino.","publisher":{"@id":"https:\/\/www.solidaridadobrera.org\/confederal\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.solidaridadobrera.org\/confederal\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.solidaridadobrera.org\/confederal\/#organization","name":"SUT Solidaridad Obrera","url":"https:\/\/www.solidaridadobrera.org\/confederal\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.solidaridadobrera.org\/confederal\/#\/schema\/logo\/image\/","url":"https:\/\/www.solidaridadobrera.org\/confederal\/wp-content\/uploads\/2021\/07\/logo_soli_web.png","contentUrl":"https:\/\/www.solidaridadobrera.org\/confederal\/wp-content\/uploads\/2021\/07\/logo_soli_web.png","width":1181,"height":1181,"caption":"SUT Solidaridad Obrera"},"image":{"@id":"https:\/\/www.solidaridadobrera.org\/confederal\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/es-es.facebook.com\/Soliobrera","https:\/\/www.instagram.com\/soliobrera\/","https:\/\/web.telegram.org\/a\/#-1001124968543"]},{"@type":"Person","@id":"https:\/\/www.solidaridadobrera.org\/confederal\/#\/schema\/person\/a9893999c35a05e0d32b4cf519d3cc62","name":"Kin_","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/f0b2c9f275a8e8670cca4a5dad715bd7d47843fb27cd0a30aea4b99dc03a2b8f?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/f0b2c9f275a8e8670cca4a5dad715bd7d47843fb27cd0a30aea4b99dc03a2b8f?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/f0b2c9f275a8e8670cca4a5dad715bd7d47843fb27cd0a30aea4b99dc03a2b8f?s=96&d=mm&r=g","caption":"Kin_"},"url":"https:\/\/www.solidaridadobrera.org\/confederal\/author\/joaquin\/"}]}},"_links":{"self":[{"href":"https:\/\/www.solidaridadobrera.org\/confederal\/wp-json\/wp\/v2\/posts\/9289","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.solidaridadobrera.org\/confederal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.solidaridadobrera.org\/confederal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.solidaridadobrera.org\/confederal\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/www.solidaridadobrera.org\/confederal\/wp-json\/wp\/v2\/comments?post=9289"}],"version-history":[{"count":14,"href":"https:\/\/www.solidaridadobrera.org\/confederal\/wp-json\/wp\/v2\/posts\/9289\/revisions"}],"predecessor-version":[{"id":9317,"href":"https:\/\/www.solidaridadobrera.org\/confederal\/wp-json\/wp\/v2\/posts\/9289\/revisions\/9317"}],"wp:attachment":[{"href":"https:\/\/www.solidaridadobrera.org\/confederal\/wp-json\/wp\/v2\/media?parent=9289"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.solidaridadobrera.org\/confederal\/wp-json\/wp\/v2\/categories?post=9289"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.solidaridadobrera.org\/confederal\/wp-json\/wp\/v2\/tags?post=9289"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}